{"id":1326,"date":"2022-02-24T05:04:17","date_gmt":"2022-02-24T05:04:17","guid":{"rendered":"https:\/\/www.tcii.com.tw\/services\/"},"modified":"2025-03-13T09:35:02","modified_gmt":"2025-03-13T09:35:02","slug":"services","status":"publish","type":"page","link":"https:\/\/www.tcii.com.tw\/en\/home\/services\/","title":{"rendered":"Services"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-1de4e81e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49a41bbc\"><h1 class=\"uagb-heading-text\">Service<gwmw style=\"display:none;\"><\/gwmw><\/h1><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-ff61b9f\" data-block-id=\"ff61b9f\"><style>.stk-ff61b9f{margin-bottom:45px !important}<\/style><p class=\"stk-block-text__text\"><\/p><\/div><body oncontextmenu=\"return false\" onselectstart=\"return false\">\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-5288a1e\" data-block-id=\"5288a1e\">\n<p class=\"stk-block-text__text\" style=\"font-size: 18px; text-align: left;\"><em><strong>Our business philosophy is to put customers first! Leveraging innovative thinking and extensive experience to provide customers with high-quality products, the most suitable solutions, and comprehensive after-sales service. Our business scope covers petrochemical industrial materials, equipment, drilling mud materials, drilling equipment, hardware supplies, as well as engineering consultation and planning.<\/strong><\/em><\/p>\n<p class=\"stk-block-text__text\" style=\"font-size: 18px; text-align: left;\"><em><strong>We have a professional team and global supply chain integration capabilities, allowing us to accurately grasp market demands and ensure the provision of efficient and competitive products and procurement services. We understand that each customer's needs are unique, so we are committed to delivering customized solutions to help optimize operational efficiency and costs.<\/strong><\/em><\/p>\n<p class=\"stk-block-text__text\" style=\"font-size: 18px; text-align: left;\"><em><strong>With professionalism and integrity, we cultivate the market, strictly control quality, and ensure the highest product standards. We not only focus on technological innovation and industry development but also emphasize environmental sustainability. Committed to providing efficient and eco-friendly solutions, we strive to drive industrial upgrades and social progress.<\/strong><\/em><\/p>\n<p class=\"stk-block-text__text\" style=\"font-size: 18px; text-align: left;\"><em><strong>For many years, we have established solid and long-term partnerships with numerous enterprises. Looking ahead, we will continue to refine our expertise, enhance our professionalism, and create greater value through exceptional services. Together with our customers, we strive to drive industry development and achieve mutual success.<\/strong><\/em><\/p>\n<\/p>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-49396577 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3839e255\">\n<div class=\"wp-block-uagb-info-box uagb-block-51cdaf42 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">1. Filler materials:                   <\/h3><\/div><p class=\"uagb-ifb-desc\">\u2022 Molecular Sieves (3A, 4A, 13X)<br>\u2022 Ceramic Saddles                          <br>\u2022 Activated Alumina                  <br>\u2022 Carbon Molecular Sieves                      <br>\u2022 Molecular Sieve Powder                      <br>\u2022 Tower Packing Materials                      <br>\u2022 Quartz Sand                          <br>\u2022 Various Material Raschig Rings           <\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2dcca7f1\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-98ba088c\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2143\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5206\u5b50\u7be91-1.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5206\u5b50\u7be91-1.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5206\u5b50\u7be91-1-300x204.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u5206\u5b50\u7be9\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2144\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5206\u5b50\u7be92-1-1024x995.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5206\u5b50\u7be92-1-1024x995.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5206\u5b50\u7be92-1-300x292.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2367\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/IMG_0110-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/IMG_0110-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/IMG_0110-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b0154a8b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-5626e70f\">\n<div class=\"wp-block-uagb-info-box uagb-block-3dd68c03 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">2. Chemical additives for slurry\/mud:                <\/h3><\/div><p class=\"uagb-ifb-desc\"> \u2022 Grade G Oil Well Cement                <br>\u2022 Portland Type II Cement                <br>\u2022 Portland Cement          <br>\u2022 Powdered Perlite                  <br>\u2022 Bentonite                         <br>\u2022 Leak-Stop Materials                     <br>\u2022 Polyacrylate Polymers      <br>\u2022 Polyacrylate Polymers      <br>       High Viscosity\/Low Viscosity Polyanionic Cellulose<br>\u2022 Barite Powder                     <br>         \u2022 Other Compounds and Raw Materials for Drilling Purposes    <\/p><\/div><\/div>\n<\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-6762d225\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2160\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u6cb9\u4e95\u6c34\u6ce5-4.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u6cb9\u4e95\u6c34\u6ce5-4.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u6cb9\u4e95\u6c34\u6ce5-4-300x150.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2153\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-1-e1741755259786-1024x995.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-1-e1741755259786-1024x995.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-1-e1741755259786-300x292.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2148\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-e1741755306387.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-e1741755306387.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-e1741755306387-300x281.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-27df38f4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-432d27bb\">\n<div class=\"wp-block-uagb-info-box uagb-block-b574ea6c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">3. Lubricant additives and greases:                            <\/h3><\/div><p class=\"uagb-ifb-desc\">              \u2022 Anti-Seize\/ Extreme Temperature Compounds<br>    \u2022 Cleaners &amp; Degreases                <br>               \u2022 Drilling Tool Joint Compounds &amp; Pipe Coatings             <br>Multi-Purpose Greases             <br>     \u2022 Multi-Purpose Greases                  <br>                \u2022 Pipe Storage Compounds                         <br>\u2022 Pump Packings                    <br>\u2022 Rust &amp; Corrosion Inhibitors                <br>\u2022 Specialty Lubricants                <br>       \u2022 Valve Lubricants                       <br>         \u2022 Valve &amp; Sealants Additives                 <br>            \u2022 Tubing, Casing &amp; Line Pipe Thread Compounds<br>             \u2022 Wireline Premium Greases &amp; Sprays<br>              \u2022 Biodegradable Products<br>     \u2022 Other Lubricants &amp; Compounds  <\/p><\/div><\/div>\n<\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-eea0f9d7\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2378\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/\u805a\u9670\u96e2\u5b50\u7e96\u7dad\u7d201.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/\u805a\u9670\u96e2\u5b50\u7e96\u7dad\u7d201.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/\u805a\u9670\u96e2\u5b50\u7e96\u7dad\u7d201-300x290.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2166\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5927\u63a5\u982d\u6f64\u6ed1\u6cb9-4-rotated.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5927\u63a5\u982d\u6f64\u6ed1\u6cb9-4-rotated.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u5927\u63a5\u982d\u6f64\u6ed1\u6cb9-4-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2155\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u7e96\u7dad\u7d201-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u7e96\u7dad\u7d201-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u7e96\u7dad\u7d201-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-65e74028 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-af7b0f60\">\n<div class=\"wp-block-uagb-info-box uagb-block-17c37038 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">       4. Industrial\/Drilling hardware materials:                         <\/h3><\/div><p class=\"uagb-ifb-desc\">   \u2022 High-Temperature Steam Hoses                <br> \u2022 High-Pressure Hoses                     <br>             \u2022 Other Specially Hoses and Joints          <br>     \u2022 Expansion Joints                 <br>\u2022 Alloy-Steel &amp; Stainless Steel Pipe<br>\u2022 Unions &amp; Adaptor           <br>\u2022 Flange &amp; Sleeve               <br>     \u2022 API Insulation Gasket\/ Washer\/ Kits<br>\u2022 High-Temperature Bolts &amp; Nuts         <br>\u2022 Grade B Bolts &amp; Nuts          <br>\u2022 Locating Bolts                 <br>\u2022 Railway Bolts &amp; Fasteners      <br>             \u2022 Other General &amp; Specially Fastener<br>\u2022 Silent Chain                 <br>\u2022 Fiber Rope                    <br>\u2022 Wire Rope             <br>\u2022 Wire                    <br>\u2022 Sling Webbing Chain            <br>\u2022 Rig Matting                 <br>\u2022 Tank Sprayer &amp; Spraying Nozzle                <br>\u2022 Pipeline Gate Valve                 <br>\u2022 Slab Gate Valve                 <br>\u2022 Air Filter Pressure Reducing Valve      <br>\u2022 Stainless Steel Flange Ball Valve      <br>\u2022 Check Valve                     <br>\u2022 Safety Valve                     <br>                  \u2022 Other General &amp; Specially Valves &amp; Fittings                    <\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-28d7b97d\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2172\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/2.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/2.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/2-300x226.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2169\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-e1741771054720-1024x731.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-e1741771054720-1024x731.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-e1741771054720-300x214.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2380\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/-scaled-e1741771020652-1024x593.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/-scaled-e1741771020652-1024x593.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/-scaled-e1741771020652-300x174.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-c411f13e\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2387\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/\u7121\u8072\u934a\u689d-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/\u7121\u8072\u934a\u689d-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/\u7121\u8072\u934a\u689d-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2386\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/3-1.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/3-1.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/3-1-300x294.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2388\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/4.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/4.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/4-300x274.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-92bfef51 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-06fdc7c3\">\n<div class=\"wp-block-uagb-info-box uagb-block-c165a411 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">       5. Industrial equipment:                       <\/h3><\/div><p class=\"uagb-ifb-desc\">           \u2022 Explosion-Proof Sludge Mixer System                <br>            \u2022 Surge Suppressor                     <br>             \u2022 Pig Indicator                      <br>     \u2022 Ultrasonic Level Transmitter          <br>\u2022 Vibration Monitoring                <br>\u2022 Air Filter                <br>\u2022 Pneumatic Diaphragm Pump                <br>\u2022 Screw Pump                        <br>                Onshore and offshore drilling rig handling tools  <br>Manual Tong and Related Assemblies            <br>\u2022 Mud Wipe                       <\/p><\/div><\/div>\n<\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-e2376ad9\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2352\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/8BD6B80D-7C82-4DF6-B476-C93A6067EDD1-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/8BD6B80D-7C82-4DF6-B476-C93A6067EDD1-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/8BD6B80D-7C82-4DF6-B476-C93A6067EDD1-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2167\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u652a\u62cc\u6a5f\u5ea7.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u652a\u62cc\u6a5f\u5ea7.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u652a\u62cc\u6a5f\u5ea7-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2168\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-scaled-e1741771754333-1024x796.jpeg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-scaled-e1741771754333-1024x796.jpeg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-scaled-e1741771754333-300x233.jpeg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-28e5cd5f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-6c6206f6\">\n<div class=\"wp-block-uagb-info-box uagb-block-c91db62f uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">       6. Engineering system planning and design:                       <\/h3><\/div><p class=\"uagb-ifb-desc\">           \u2022 Continuous Flow Monitoring System                <br>                \u2022 Soft Water System Accessories and Maintenance                 <br>             \u2022 Ozone Recovery System              <br>Top Drive                    <br>Marine hydraulic systems            <br>Anti-static feeding system        <br>Tank renovation or modification        <br>Water Treatment System                   <br>Exhaust Pipe      <br>Drilling machine mechanism system           <\/p><\/div><\/div>\n<\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-3f8b9f87\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2360\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/B9D5B00B-9891-41FD-B055-E84FFB7FAE6B-L0-001_0-e1741772151348-758x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/B9D5B00B-9891-41FD-B055-E84FFB7FAE6B-L0-001_0-e1741772151348-758x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/B9D5B00B-9891-41FD-B055-E84FFB7FAE6B-L0-001_0-e1741772151348-222x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2173\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-scaled-e1741772308307-1024x620.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-scaled-e1741772308307-1024x620.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/-scaled-e1741772308307-300x182.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2353\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/17FA9B0C-034C-4A12-84AD-077D821FEF4B-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/17FA9B0C-034C-4A12-84AD-077D821FEF4B-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/17FA9B0C-034C-4A12-84AD-077D821FEF4B-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-03114851 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-e2c59227\">\n<div class=\"wp-block-uagb-info-box uagb-block-e250c1cf uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">       7. Others:                                     <\/h3><\/div><p class=\"uagb-ifb-desc\">               \u2022 Drilling Explosives and Oilwell Tools                <br>                \u2022 Herbicides &amp; Pesticide                             <br>            <br>        Please contact our customer service with your request,<br>                 and we will arrange for a representative to get in touch with you promptly.                          <br>                           <\/p><\/div><\/div>\n<\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-070790f7\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2171\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u522e\u6ce5\u76e4.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u522e\u6ce5\u76e4.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/\u522e\u6ce5\u76e4-300x224.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2174\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-1024x769.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-1024x769.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/1-300x225.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u793a\u610f\u5716\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"2369\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/IMG_0128-768x1024.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/IMG_0128-768x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2025\/03\/IMG_0128-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\t\u73fe\u5834\u4f5c\u696d\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-8919b31\" data-block-id=\"8919b31\"><p class=\"stk-block-text__text\"><\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>\u670d\u52d9\u9805\u76ee \u672c\u516c\u53f8\u79c9\u6301\u300c\u4ee5\u5ba2\u70ba\u5c0a\u300d\u7684\u7d93\u71df\u7406\u5ff5\uff0c\u6191\u85c9\u5275\u65b0\u7684\u601d\u7dad\u8207\u8c50\u5bcc\u7684\u7d93\u9a57\uff0c\u63d0\u4f9b\u5ba2\u6236\u9ad8\u54c1\u8cea\u7684\u7522\u54c1\u3001\u6700\u9069\u5207\u7684\u89e3\u6c7a\u65b9\u6848 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1322,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1326","page","type-page","status-publish","hentry"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":""},"post_excerpt_stackable":"<p>\u670d\u52d9\u9805\u76ee \u672c\u516c\u53f8\u79c9\u6301\u300c\u4ee5\u5ba2\u70ba\u5c0a\u300d\u7684\u7d93\u71df\u7406\u5ff5\uff0c\u6191\u85c9\u5275\u65b0\u7684\u601d\u7dad\u8207\u8c50\u5bcc\u7684\u7d93\u9a57\uff0c\u63d0\u4f9b\u5ba2\u6236\u9ad8\u54c1\u8cea\u7684\u7522\u54c1\u3001\u6700\u9069\u5207\u7684\u89e3\u6c7a\u65b9\u6848\u8207\u5b8c\u5584\u7684\u552e\u5f8c\u670d\u52d9\u3002\u6211\u5011\u7684\u696d\u52d9\u7bc4\u7587\u6db5\u84cb\u77f3\u5316\u5de5\u696d\u7528\u6599\u3001\u8a2d\u5099\u3001\u947d\u4e95\u6ce5\u6f3f\u7528\u6599\u3001\u947d\u4e95\u8a2d\u5099\u3001\u4e94\u91d1\u6750\u6599\uff0c&hellip;<\/p>\n","category_list":"","author_info":{"name":"admin","url":"https:\/\/www.tcii.com.tw\/en\/author\/admin\/"},"comments_num":"0 comments","spectra_custom_meta":{"stackable_optimized_css":[""],"stackable_optimized_css_raw":["a:0:{}"],"site-sidebar-layout":["no-sidebar"],"site-content-layout":["page-builder"],"site-post-title":["disabled"],"ast-featured-img":["disabled"],"theme-transparent-header-meta":["enabled"],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"astra-main-page-id":["59764"],"ast_self_id_59764":["1"],"_yoast_wpseo_content_score":["90"],"_wxr_import_user_slug":["kalpeshb"],"_astra_sites_imported_post":["1"],"_astra_sites_enable_for_batch":["1"],"_edit_last":["1"],"_wp_page_template":["default"],"_edit_lock":["1747904013:1"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"93143ae93db62ba35280a72c9f66a175\";s:6:\"images\";a:1:{i:0;i:2143;}}"],"rank_math_internal_links_processed":["1"],"footnotes":[""],"rank_math_seo_score":["9"],"_uag_custom_page_level_css":[""],"ast-site-content-layout":["full-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":["set"],"_uag_css_file_name":["uag-css-1326.css"],"astra_style_timestamp_css":["1778819107"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:224155:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-slide .spectra-image-gallery__media-wrapper{display:block !important}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow .25s;-moz-transition:box-shadow .25s;-o-transition:box-shadow .25s;transition:box-shadow .25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter .5s,transform .5s;-moz-transition:filter .5s,transform .5s;-o-transition:filter .5s,transform .5s;transition:filter .5s,transform .5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow .25s,-webkit-backdrop-filter .5s;-moz-transition:box-shadow .25s,backdrop-filter .5s;-o-transition:box-shadow .25s,backdrop-filter .5s;transition:box-shadow .25s,backdrop-filter .5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color .25s;-moz-transition:background-color .25s;-o-transition:background-color .25s;transition:background-color .25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:rgba(0,0,0,0);padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-arrows:disabled{opacity:.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:rgba(0,0,0,0);border:0;outline:none;background:rgba(0,0,0,0);-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-button.disabled{opacity:.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:.5em;background-color:rgba(0,0,0,0);border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0, 0, 0, 0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:.5;transform:scale(75%);-webkit-transition-property:opacity,transform;-moz-transition-property:opacity,transform;-o-transition-property:opacity,transform;transition-property:opacity,transform;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:rgba(0,0,0,0);border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:rgba(0,0,0,0);transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media(max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media(max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-1de4e81e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1de4e81e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1de4e81e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1de4e81e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1de4e81e .uagb-container__video-wrap video{opacity: 0;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1de4e81e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1de4e81e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1de4e81e{min-height: 420px;box-shadow: 0px 50px 50px -30px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 48% 61%;background-size: 100%;background-attachment: scroll;background-image: url(https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/sunset-factory-buildings-6226244.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1de4e81e::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: rgba(35,35,35,0.16);opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-49a41bbc.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-49a41bbc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-49a41bbc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a41bbc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-49a41bbc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-49396577 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-49396577 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-49396577 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-49396577 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-49396577 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49396577{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49396577 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-49396577{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3839e255 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3839e255 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3839e255 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3839e255 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3839e255 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3839e255{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3839e255 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3839e255{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-51cdaf42 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-51cdaf42 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-51cdaf42 .uagb-ifb-icon svg{fill: #333;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51cdaf42 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51cdaf42 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51cdaf42 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51cdaf42 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-51cdaf42 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-51cdaf42 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-51cdaf42 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-51cdaf42 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-51cdaf42 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-51cdaf42 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-51cdaf42 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-51cdaf42.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-51cdaf42 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-2dcca7f1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2dcca7f1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2dcca7f1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2dcca7f1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2dcca7f1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2dcca7f1{max-width: 75%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2dcca7f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2dcca7f1{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-98ba088c.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-98ba088c .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-98ba088c .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-98ba088c .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-98ba088c .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-98ba088c .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-98ba088c .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-98ba088c .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-98ba088c .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-98ba088c .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-98ba088c .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088cspectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-98ba088c .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-98ba088c .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-b0154a8b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b0154a8b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b0154a8b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b0154a8b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b0154a8b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0154a8b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0154a8b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b0154a8b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5626e70f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5626e70f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5626e70f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5626e70f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5626e70f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5626e70f{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5626e70f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5626e70f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-3dd68c03 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3dd68c03 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3dd68c03 .uagb-ifb-icon svg{fill: #333;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3dd68c03 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3dd68c03 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3dd68c03 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3dd68c03 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3dd68c03 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-3dd68c03 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-3dd68c03 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3dd68c03 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3dd68c03 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3dd68c03 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3dd68c03 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-3dd68c03.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3dd68c03 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6762d225.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-6762d225 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-6762d225 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-6762d225 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-6762d225 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-6762d225 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-6762d225 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-6762d225 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-6762d225 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-6762d225 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-6762d225 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-6762d225 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-6762d225 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-27df38f4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27df38f4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27df38f4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27df38f4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27df38f4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27df38f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27df38f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-27df38f4{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-432d27bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-432d27bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-432d27bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-432d27bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-432d27bb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-432d27bb{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-432d27bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-432d27bb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-b574ea6c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b574ea6c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b574ea6c .uagb-ifb-icon svg{fill: #333;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b574ea6c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b574ea6c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b574ea6c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b574ea6c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b574ea6c .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-b574ea6c .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-b574ea6c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b574ea6c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b574ea6c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b574ea6c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b574ea6c .uagb-infobox__content-wrap{text-align: center;}.uagb-block-b574ea6c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b574ea6c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-eea0f9d7.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-eea0f9d7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-eea0f9d7 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-65e74028 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-65e74028 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-65e74028 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-65e74028 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-65e74028 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-65e74028{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-65e74028 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-65e74028{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-af7b0f60 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-af7b0f60 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-af7b0f60 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-af7b0f60 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-af7b0f60 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af7b0f60{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af7b0f60 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-af7b0f60{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-17c37038 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-17c37038 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-17c37038 .uagb-ifb-icon svg{fill: #333;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-17c37038 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-17c37038 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17c37038 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-17c37038.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17c37038 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-17c37038 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-17c37038 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-17c37038 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-17c37038 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-17c37038 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-17c37038 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-17c37038 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-17c37038.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-17c37038 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-17c37038.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-28d7b97d.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-28d7b97d .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-28d7b97d .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-28d7b97d .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-28d7b97d .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-28d7b97d .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-28d7b97d .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-28d7b97d .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-28d7b97d .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97dspectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-28d7b97d .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-28d7b97d .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.uagb-block-c411f13e.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-c411f13e .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-c411f13e .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-c411f13e .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-c411f13e .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-c411f13e .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-c411f13e .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-c411f13e .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-c411f13e .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-c411f13e .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-c411f13e .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13espectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-c411f13e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-c411f13e .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-92bfef51 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92bfef51 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92bfef51 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-92bfef51 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-92bfef51 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92bfef51{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92bfef51 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-92bfef51{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-06fdc7c3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-06fdc7c3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-06fdc7c3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-06fdc7c3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-06fdc7c3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-06fdc7c3{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-06fdc7c3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-06fdc7c3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-c165a411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c165a411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c165a411 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c165a411 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c165a411 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c165a411 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c165a411.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c165a411 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c165a411 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-c165a411 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-c165a411 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c165a411 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c165a411 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c165a411 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c165a411 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-c165a411.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c165a411 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-c165a411.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e2376ad9.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-e2376ad9 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-e2376ad9 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-e2376ad9 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-e2376ad9 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-e2376ad9 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-e2376ad9 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-e2376ad9 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-e2376ad9 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-e2376ad9 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-28e5cd5f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-28e5cd5f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-28e5cd5f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-28e5cd5f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-28e5cd5f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-28e5cd5f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-28e5cd5f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-28e5cd5f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6c6206f6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6c6206f6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6c6206f6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6c6206f6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6c6206f6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6c6206f6{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6c6206f6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6c6206f6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-c91db62f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c91db62f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c91db62f .uagb-ifb-icon svg{fill: #333;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c91db62f .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c91db62f .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c91db62f .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c91db62f.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c91db62f .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c91db62f .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-c91db62f .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-c91db62f .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c91db62f .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c91db62f .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c91db62f .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c91db62f .uagb-infobox__content-wrap{text-align: center;}.uagb-block-c91db62f.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c91db62f .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-3f8b9f87.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-3f8b9f87 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-3f8b9f87 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-03114851 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03114851 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03114851 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03114851 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03114851 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03114851{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03114851 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-03114851{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e2c59227 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e2c59227 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e2c59227 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e2c59227 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e2c59227 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e2c59227{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e2c59227 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e2c59227{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-e250c1cf .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e250c1cf .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e250c1cf .uagb-ifb-icon svg{fill: #333;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e250c1cf .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e250c1cf .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e250c1cf .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e250c1cf .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e250c1cf .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-e250c1cf .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-e250c1cf .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e250c1cf .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e250c1cf .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e250c1cf .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e250c1cf .uagb-infobox__content-wrap{text-align: center;}.uagb-block-e250c1cf.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e250c1cf .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-070790f7.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-070790f7 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-070790f7 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-070790f7 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-070790f7 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-070790f7 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-070790f7 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-070790f7 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-070790f7 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-070790f7 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-070790f7 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-070790f7 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-070790f7 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-1de4e81e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1de4e81e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1de4e81e{min-height: 50vh;padding-top: 100px;padding-bottom: 100px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/sunset-factory-buildings-6226244.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-1de4e81e::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: rgba(35,35,35,0.16);opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49396577{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49396577 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-49396577{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3839e255{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3839e255 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3839e255{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-51cdaf42 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-51cdaf42 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-51cdaf42 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2dcca7f1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2dcca7f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2dcca7f1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-98ba088c.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-98ba088c .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-98ba088c .spectra-image-gallery__control-button{padding:    ;}.uagb-block-98ba088c .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0154a8b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0154a8b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b0154a8b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5626e70f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5626e70f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5626e70f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3dd68c03 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3dd68c03 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3dd68c03 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6762d225.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-6762d225 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-6762d225 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-6762d225 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27df38f4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27df38f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-27df38f4{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-432d27bb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-432d27bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-432d27bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b574ea6c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b574ea6c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b574ea6c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-eea0f9d7.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-65e74028{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-65e74028 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-65e74028{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af7b0f60{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af7b0f60 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-af7b0f60{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-17c37038 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-17c37038 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-17c37038 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-28d7b97d.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-28d7b97d .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-28d7b97d .spectra-image-gallery__control-button{padding:    ;}.uagb-block-28d7b97d .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-c411f13e.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-c411f13e .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-c411f13e .spectra-image-gallery__control-button{padding:    ;}.uagb-block-c411f13e .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92bfef51{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92bfef51 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-92bfef51{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-06fdc7c3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-06fdc7c3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-06fdc7c3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c165a411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c165a411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c165a411 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e2376ad9.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-e2376ad9 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-e2376ad9 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-28e5cd5f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-28e5cd5f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-28e5cd5f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6c6206f6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6c6206f6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6c6206f6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c91db62f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c91db62f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c91db62f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-3f8b9f87.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03114851{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03114851 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-03114851{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e2c59227{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e2c59227 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e2c59227{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e250c1cf .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e250c1cf .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e250c1cf .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-070790f7.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-070790f7 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-070790f7 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-070790f7 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-1de4e81e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1de4e81e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1de4e81e{min-height: 50vh;padding-top: 50px;padding-bottom: 50px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.tcii.com.tw\/wp-content\/uploads\/2023\/08\/sunset-factory-buildings-6226244.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-1de4e81e::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: rgba(35,35,35,0.16);opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49396577{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49396577 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-49396577{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3839e255{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3839e255 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3839e255{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-51cdaf42 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-51cdaf42 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-51cdaf42 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-51cdaf42.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2dcca7f1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2dcca7f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2dcca7f1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-98ba088c.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-98ba088c .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-98ba088c .spectra-image-gallery__control-button{padding:    ;}.uagb-block-98ba088c .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-98ba088c .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-98ba088c .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-98ba088c+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0154a8b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0154a8b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b0154a8b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5626e70f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5626e70f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5626e70f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3dd68c03 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3dd68c03 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3dd68c03 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3dd68c03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6762d225.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-6762d225 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-6762d225 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-6762d225 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-6762d225 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-6762d225 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-6762d225+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27df38f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27df38f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-27df38f4{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-432d27bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-432d27bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-432d27bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b574ea6c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b574ea6c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b574ea6c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b574ea6c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-eea0f9d7.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-eea0f9d7 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-eea0f9d7 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-eea0f9d7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-65e74028{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-65e74028 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-65e74028{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af7b0f60{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af7b0f60 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-af7b0f60{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-17c37038 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-17c37038 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-17c37038 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-17c37038 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-17c37038.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-17c37038.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-28d7b97d.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-28d7b97d .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-28d7b97d .spectra-image-gallery__control-button{padding:    ;}.uagb-block-28d7b97d .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-28d7b97d .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-28d7b97d .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-28d7b97d+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.uagb-block-c411f13e.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-c411f13e .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-c411f13e .spectra-image-gallery__control-button{padding:    ;}.uagb-block-c411f13e .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-c411f13e .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-c411f13e .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-c411f13e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-92bfef51{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-92bfef51 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-92bfef51{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-06fdc7c3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-06fdc7c3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-06fdc7c3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c165a411 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c165a411 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c165a411 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c165a411 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c165a411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c165a411.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e2376ad9.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-e2376ad9 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-e2376ad9 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-e2376ad9 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-e2376ad9 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-e2376ad9+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-28e5cd5f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-28e5cd5f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-28e5cd5f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6c6206f6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6c6206f6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6c6206f6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c91db62f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c91db62f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c91db62f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c91db62f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c91db62f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-3f8b9f87.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-3f8b9f87 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-3f8b9f87 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-3f8b9f87+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03114851{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03114851 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-03114851{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e2c59227{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e2c59227 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e2c59227{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e250c1cf .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e250c1cf .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e250c1cf .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e250c1cf.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-070790f7.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-070790f7 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-070790f7 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-070790f7 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-070790f7 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-070790f7 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-070790f7+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:18:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:9:\"core\/html\";i:3;s:14:\"core\/paragraph\";i:6;s:13:\"uagb\/info-box\";i:8;s:18:\"uagb\/image-gallery\";i:9;s:12:\"core\/columns\";i:10;s:11:\"core\/column\";i:11;s:10:\"core\/group\";i:12;s:14:\"stackable\/text\";i:13;s:11:\"core\/search\";i:15;s:12:\"core\/heading\";i:16;s:17:\"core\/latest-posts\";i:17;s:20:\"core\/latest-comments\";i:18;s:13:\"core\/archives\";i:19;s:15:\"core\/categories\";i:20;s:10:\"core\/image\";i:21;s:9:\"core\/list\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788307899\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.tcii.com.tw\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"\u670d\u52d9\u9805\u76ee \u672c\u516c\u53f8\u79c9\u6301\u300c\u4ee5\u5ba2\u70ba\u5c0a\u300d\u7684\u7d93\u71df\u7406\u5ff5\uff0c\u6191\u85c9\u5275\u65b0\u7684\u601d\u7dad\u8207\u8c50\u5bcc\u7684\u7d93\u9a57\uff0c\u63d0\u4f9b\u5ba2\u6236\u9ad8\u54c1\u8cea\u7684\u7522\u54c1\u3001\u6700\u9069\u5207\u7684\u89e3\u6c7a\u65b9\u6848&hellip;","_links":{"self":[{"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/pages\/1326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/comments?post=1326"}],"version-history":[{"count":59,"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/pages\/1326\/revisions"}],"predecessor-version":[{"id":2418,"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/pages\/1326\/revisions\/2418"}],"up":[{"embeddable":true,"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/pages\/1322"}],"wp:attachment":[{"href":"https:\/\/www.tcii.com.tw\/en\/wp-json\/wp\/v2\/media?parent=1326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}